{"id":706,"count":27,"description":"","link":"http:\/\/metropoliagzm.pl\/de\/tag\/koleje-slaskie\/","name":"Koleje \u015al\u0105skie","slug":"koleje-slaskie","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Koleje \u015al\u0105skie - Metropolia GZM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metropoliagzm.pl\/de\/tag\/koleje-slaskie\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Koleje \u015al\u0105skie - Metropolia GZM\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/tag\\\/koleje-slaskie\\\/\",\"url\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/tag\\\/koleje-slaskie\\\/\",\"name\":\"Koleje \u015al\u0105skie - Metropolia GZM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/tag\\\/koleje-slaskie\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/tag\\\/koleje-slaskie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/metropoliagzm.pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Koleje \u015al\u0105skie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/\",\"name\":\"Metropolia GZM\",\"description\":\"Oficjalny portal G\u00f3rno\u015bl\u0105sko-Zag\u0142\u0119biowskiej Metropolii\",\"publisher\":{\"@id\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/#organization\",\"name\":\"Metropolia GZM\",\"url\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/metropoliagzm.pl\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Sygnet-strona-glowna.png\",\"contentUrl\":\"https:\\\/\\\/metropoliagzm.pl\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Sygnet-strona-glowna.png\",\"width\":36,\"height\":45,\"caption\":\"Metropolia GZM\"},\"image\":{\"@id\":\"https:\\\/\\\/metropoliagzm.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Koleje \u015al\u0105skie - Metropolia GZM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metropoliagzm.pl\/de\/tag\/koleje-slaskie\/","twitter_card":"summary_large_image","twitter_title":"Koleje \u015al\u0105skie - Metropolia GZM","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/metropoliagzm.pl\/en\/tag\/koleje-slaskie\/","url":"https:\/\/metropoliagzm.pl\/en\/tag\/koleje-slaskie\/","name":"Koleje \u015al\u0105skie - Metropolia GZM","isPartOf":{"@id":"https:\/\/metropoliagzm.pl\/en\/#website"},"breadcrumb":{"@id":"https:\/\/metropoliagzm.pl\/en\/tag\/koleje-slaskie\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/metropoliagzm.pl\/en\/tag\/koleje-slaskie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/metropoliagzm.pl\/"},{"@type":"ListItem","position":2,"name":"Koleje \u015al\u0105skie"}]},{"@type":"WebSite","@id":"https:\/\/metropoliagzm.pl\/en\/#website","url":"https:\/\/metropoliagzm.pl\/en\/","name":"Metropolia GZM","description":"Oficjalny portal G\u00f3rno\u015bl\u0105sko-Zag\u0142\u0119biowskiej Metropolii","publisher":{"@id":"https:\/\/metropoliagzm.pl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metropoliagzm.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/metropoliagzm.pl\/en\/#organization","name":"Metropolia GZM","url":"https:\/\/metropoliagzm.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/metropoliagzm.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/metropoliagzm.pl\/wp-content\/uploads\/2019\/03\/Sygnet-strona-glowna.png","contentUrl":"https:\/\/metropoliagzm.pl\/wp-content\/uploads\/2019\/03\/Sygnet-strona-glowna.png","width":36,"height":45,"caption":"Metropolia GZM"},"image":{"@id":"https:\/\/metropoliagzm.pl\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/metropoliagzm.pl\/de\/wp-json\/wp\/v2\/tags\/706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/metropoliagzm.pl\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/metropoliagzm.pl\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/metropoliagzm.pl\/de\/wp-json\/wp\/v2\/posts?tags=706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}